{"id":294934,"date":"2025-04-07T10:52:58","date_gmt":"2025-04-07T13:52:58","guid":{"rendered":"https:\/\/emfoco.med.br\/dr-ricardo-guerra\/"},"modified":"2025-09-10T08:34:22","modified_gmt":"2025-09-10T11:34:22","slug":"dr-ricardo-guerra","status":"publish","type":"project","link":"https:\/\/emfoco.med.br\/es\/dr-ricardo-guerra\/","title":{"rendered":"Dr. Ricardo Guerra"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.24.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb10px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_3,2_3&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb1&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb max_width=\u00bb100%\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb0px|20px|0px|20px|true|true\u00bb border_color_all=\u00bb#c1eae9&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px||20px||true|false\u00bb border_radii=\u00bboff|20px|||20px\u00bb border_width_all=\u00bb5px\u00bb border_color_all=\u00bb#13678a\u00bb global_colors_info=\u00bb{}\u00bb][difl_advanced_person ap_photo=\u00bbhttps:\/\/emfoco.med.br\/wp-content\/uploads\/2025\/04\/Perfil-Medico-MEF-Ricardo-Guerra.webp\u00bb ap_name=\u00bbDr. Ricardo Guerra\u00bb ap_description=\u00bb<\/p>\n<p>CRM-SP <span style=%22font-weight: 400;%22>185442<\/span><span style=%22font-weight: 400;%22><\/span><\/p>\n<p><span style=%22font-weight: 400;%22><\/span>RQE <span style=%22font-weight: 400;%22>99421<\/span><span style=%22font-weight: 400;%22><\/span><\/p>\n<p><span style=%22font-weight: 400;%22><\/span>RQE <span style=%22font-weight: 400;%22>99422<\/span><\/p>\n<p>\u00bb ap_name_tag=\u00bbh1&#8243; module_wrapper_margin=\u00bb||40px||false|false\u00bb name_margin=\u00bb30px||||false|false\u00bb description_margin=\u00bb10px||||false|false\u00bb image_margin=\u00bb||||false|false\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb name_text_align=\u00bbcenter\u00bb name_font_size=\u00bb28px\u00bb description_text_align=\u00bbcenter\u00bb description_text_color=\u00bbrgba(10,10,10,0.56)\u00bb description_font_size=\u00bb18px\u00bb description_line_height=\u00bb0.5em\u00bb custom_margin=\u00bb||||false|false\u00bb custom_css_main_element=\u00bbtext-align: center;\u00bb border_radii_photo_border=\u00bbon|200px|200px|200px|200px\u00bb border_width_all_photo_border=\u00bb5px\u00bb border_color_all_photo_border=\u00bb#13678a\u00bb global_colors_info=\u00bb{}\u00bb][\/difl_advanced_person][difl_dual_button btn_left_background_bgcolor=\u00bb#13678a\u00bb btn_left_font_icon=\u00bb&#xe023;||divi||400&#8243; btn_left_icon_color=\u00bb#FFFFFF\u00bb btn_left_icon_placement=\u00bbleft\u00bb btn_right_background_background_image=\u00bbhttps:\/\/emfoco.med.br\/wp-content\/uploads\/2024\/02\/iconewhatsapp1.webp\u00bb btn_right_background_background_image_size=\u00bbfit\u00bb btn_right_background_size_width=\u00bb100%\u00bb btn_right_background_size_height=\u00bb100%\u00bb use_right_button_icon=\u00bboff\u00bb left_button=\u00bbReservar en l\u00ednea\u00bb left_button_url=\u00bbhttps:\/\/api.whatsapp.com\/send\/?phone=\u200e551132893195&amp;text=Ol%C3%A1%2C+vim+do+site+e+gostaria+de+mais+informa%C3%A7%C3%B5es+sobre+exame+com+o+Dr.+Ricardo+Guerra.&amp;type=phone_number&amp;app_absent=0&#8243; right_button=\u00bb_\u00bb right_button_url=\u00bbhttps:\/\/api.whatsapp.com\/send\/?phone=\u200e551132893195&amp;text=Ol%C3%A1%2C+vim+do+site+e+gostaria+de+mais+informa%C3%A7%C3%B5es+sobre+exame+com+o+Dr.+Ricardo+Guerra.&amp;type=phone_number&amp;app_absent=0&#8243; right_button_target=\u00bbon\u00bb right_button_wrapper_margin=\u00bb|||50px|false|false\u00bb alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb left_button_text_color=\u00bb#FFFFFF\u00bb right_button_text_color=\u00bb#FFFFFF\u00bb right_button_font_size=\u00bb22px\u00bb border_radii_left_button=\u00bbon|10px|10px|10px|10px\u00bb global_colors_info=\u00bb{}\u00bb][\/difl_dual_button][\/et_pb_column][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb2%||1%||false|false\u00bb border_radii=\u00bboff||20px|20px|\u00bb border_width_all=\u00bb5px\u00bb border_color_all=\u00bb#13678a\u00bb border_width_left=\u00bb0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_2_font_size=\u00bb18px\u00bb header_2_line_height=\u00bb1.8em\u00bb header_3_font=\u00bb||||||||\u00bb header_3_text_color=\u00bb#116789&#8243; header_3_line_height=\u00bb2em\u00bb header_5_text_color=\u00bb#116789&#8243; header_5_line_height=\u00bb0.8em\u00bb width=\u00bb90%\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Mi historia<\/h2>\n<p><a href=\"https:\/\/emfoco.med.br\/medico-endoscopista-conheca-o-dr-ricardo-guerra\/\" target=\"_blank\" rel=\"noopener\">El Dr. Ricardo Guerra Almeida<\/a> es endoscopista por la Escola Paulista de Medicina da Universidade Federal de S\u00e3o Paulo (EPM\/UNIFESP). Se ha subespecializado en Fisiolog\u00eda Gastrointestinal en el Hospital Israelita Albert Einstein y en Colangiopancreatograf\u00eda Endosc\u00f3pica Retr\u00f3grada en el Hospital Sancta Maggiore &#8211; Instituto Prevent Senior. <\/p>\n<p>Trabaja principalmente en el diagn\u00f3stico de enfermedades esof\u00e1gicas y en pruebas como la monitorizaci\u00f3n del pH y la manometr\u00eda esof\u00e1gica.<\/p>\n<p class=\"font_6\">[\/et_pb_text][difl_faq faq_layout=\u00bbtoggle\u00bb close_icon_color=\u00bb#13678a\u00bb faq_wrapper_margin=\u00bb30px||30px|44px|false|false\u00bb faq_item_wrapper_margin=\u00bb||||false|false\u00bb faq_item_per_column_tablet=\u00bb2&#8243; faq_item_per_column_phone=\u00bb1&#8243; faq_item_per_column_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb question_text_font_size=\u00bb18px\u00bb width=\u00bb60%\u00bb border_width_all_faq_item_wrapper_border=\u00bb0px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb que_wrapper_bg_bgcolor__hover=\u00bb1px||||false|false\u00bb que_wrapper_bg_bgcolor__hover_enabled=\u00bbon|hover\u00bb][difl_faqitem question=\u00bbEspecialidade m\u00e9dica\u00bb ans_img_padding=\u00bb||||false|false\u00bb _builder_version=\u00bb4.27.4&#8243; global_colors_info=\u00bb{}\u00bb que_wrapper_bg_bgcolor__hover=\u00bb1px||||false|false\u00bb que_wrapper_bg_bgcolor__hover_enabled=\u00bbon|hover\u00bb]<\/p>\n<p>Endoscopia<\/p>\n<p>[\/difl_faqitem][difl_faqitem question=\u00bbSubespecializa\u00e7\u00e3o\u00bb ans_img_padding=\u00bb||||false|false\u00bb _builder_version=\u00bb4.27.4&#8243; global_colors_info=\u00bb{}\u00bb que_wrapper_bg_bgcolor__hover=\u00bb1px||||false|false\u00bb que_wrapper_bg_bgcolor__hover_enabled=\u00bbon|hover\u00bb]<\/p>\n<p>Fisiologia Gastrointestinal<\/p>\n<p>Colangiopancreatografia Endosc\u00f3pica Retr\u00f3grada<\/p>\n<p>[\/difl_faqitem][difl_faqitem question=\u00bbHospitais de refer\u00eancia\u00bb ans_img_padding=\u00bb||||false|false\u00bb _builder_version=\u00bb4.27.4&#8243; global_colors_info=\u00bb{}\u00bb que_wrapper_bg_bgcolor__hover=\u00bb1px||||false|false\u00bb que_wrapper_bg_bgcolor__hover_enabled=\u00bbon|hover\u00bb]<\/p>\n<p>Hospital S\u00e3o Paulo<\/p>\n<p>Hospital S\u00e3o Crist\u00f3v\u00e3o<\/p>\n<p>Hospital Prevent Senior<\/p>\n<p>[\/difl_faqitem][difl_faqitem question=\u00bbForma\u00e7\u00e3o profissional\u00bb ans_img_padding=\u00bb||||false|false\u00bb _builder_version=\u00bb4.27.4&#8243; global_colors_info=\u00bb{}\u00bb que_wrapper_bg_bgcolor__hover=\u00bb1px||||false|false\u00bb que_wrapper_bg_bgcolor__hover_enabled=\u00bbon|hover\u00bb]<\/p>\n<h6 class=\"font_6\">Gradua\u00e7\u00e3o:<\/h6>\n<ul>\n<li class=\"font_6\">Centro Universit\u00e1rio do Estado do Par\u00e1<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h6 class=\"font_6\">Resid\u00eancias:<\/h6>\n<ul>\n<li class=\"font_6\">Cl\u00ednica M\u00e9dica pela Escola Paulista de Medicina da Universidade Federal de S\u00e3o Paulo (EPM\/UNIFESP).<\/li>\n<li class=\"font_6\">Endoscopia pela Escola Paulista de Medicina da Universidade Federal de S\u00e3o Paulo (EPM\/UNIFESP).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h6>Subespecializa\u00e7\u00f5es e aperfei\u00e7oamentos:<\/h6>\n<ul>\n<li>Fisiologia Gastrointestinal pelo Hospital Israelita Albert Einstein<\/li>\n<li>Colangiopancreatografia Endosc\u00f3pica Retr\u00f3grada pelo Hospital Sancta Maggiore &#8211; Instituto Prevent Senior<\/li>\n<\/ul>\n<ul class=\"font_6\"><\/ul>\n<ul class=\"font_6\"><\/ul>\n<ul class=\"font_6\"><\/ul>\n<ul class=\"font_6\"><\/ul>\n<ul class=\"font_6\"><\/ul>\n<ul class=\"font_6\"><\/ul>\n<ul class=\"font_6\"><\/ul>\n<ul class=\"font_6\"><\/ul>\n<p>[\/difl_faqitem][difl_faqitem question=\u00bb\u00c1reas de atua\u00e7\u00e3o e experi\u00eancia profissional\u00bb ans_img_padding=\u00bb||||false|false\u00bb _builder_version=\u00bb4.27.4&#8243; global_colors_info=\u00bb{}\u00bb que_wrapper_bg_bgcolor__hover=\u00bb1px||||false|false\u00bb que_wrapper_bg_bgcolor__hover_enabled=\u00bbon|hover\u00bb]<\/p>\n<h6>Endoscopia:<\/h6>\n<ul>\n<li>Endoscopia Digestiva Alta<\/li>\n<li>Endoscopia Digestiva Baixa<\/li>\n<li>Colangiopancreatografia Endosc\u00f3pica Retr\u00f3grada<\/li>\n<li>Manometria esof\u00e1gica<\/li>\n<li>pHmetria esof\u00e1gica<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h6>Fisiologia gastrointestinal:<\/h6>\n<ul>\n<li>Acalasia idiop\u00e1tica<\/li>\n<li>Altera\u00e7\u00f5es motoras do es\u00f4fago<\/li>\n<li>Dificuldade ou dor para engolir<\/li>\n<li>Disfagias faringo-esof\u00e1gicas<\/li>\n<li>Disfagias funcionais<\/li>\n<li>Divert\u00edculos do es\u00f4fago<\/li>\n<li>Doen\u00e7a do refluxo gastroesof\u00e1gico<\/li>\n<li>Dor tor\u00e1cica de origem n\u00e3o card\u00edaca<\/li>\n<li>Engasgo<\/li>\n<li>Esclerodermia<\/li>\n<li>Espasmo difuso<\/li>\n<li>Impedanciophmetria esof\u00e1gica<\/li>\n<li>Localiza\u00e7\u00e3o da sonda de pH<\/li>\n<li>Megaes\u00f4fago<\/li>\n<li>N\u00e1useas recorrentes<\/li>\n<li>Pr\u00e9-operat\u00f3rio<\/li>\n<li>Queima\u00e7\u00e3o retroesternal<\/li>\n<li>Regurgita\u00e7\u00e3o alimentar<\/li>\n<li>Sensa\u00e7\u00e3o de entalamento<\/li>\n<li>V\u00f4mitos recorrentes<\/li>\n<\/ul>\n<ul><\/ul>\n<p>&nbsp;<\/p>\n<p>[\/difl_faqitem][\/difl_faq][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bboff|off|on\u00bb _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.24.2&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb max_width=\u00bb100%\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb0px|5px|0px|5px|true|true\u00bb border_color_all=\u00bb#c1eae9&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px||20px||true|false\u00bb border_radii=\u00bboff|20px|20px|20px|20px\u00bb border_width_all=\u00bb5px\u00bb border_color_all=\u00bb#13678a\u00bb global_colors_info=\u00bb{}\u00bb][difl_advanced_person ap_photo=\u00bbhttps:\/\/emfoco.med.br\/wp-content\/uploads\/2025\/04\/Perfil-Medico-MEF-Ricardo-Guerra.webp\u00bb image_wrapper_max_width=\u00bb60%\u00bb ap_name=\u00bbDr. Ricardo Guerra\u00bb ap_description=\u00bb<\/p>\n<p>CRM-SP <span style=%22font-weight: 400;%22>185442<\/span><span style=%22font-weight: 400;%22><\/span><\/p>\n<p><span style=%22font-weight: 400;%22><\/span>RQE <span style=%22font-weight: 400;%22>99421<\/span><span style=%22font-weight: 400;%22><\/span><\/p>\n<p><span style=%22font-weight: 400;%22><\/span>RQE <span style=%22font-weight: 400;%22>99422<\/span><\/p>\n<p>\u00bb module_wrapper_margin=\u00bb||40px||false|false\u00bb name_margin=\u00bb30px||||false|false\u00bb description_margin=\u00bb10px||||false|false\u00bb image_margin=\u00bb||||false|false\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb name_text_align=\u00bbcenter\u00bb description_text_align=\u00bbcenter\u00bb description_text_color=\u00bbrgba(10,10,10,0.56)\u00bb description_line_height=\u00bb0.5em\u00bb custom_margin=\u00bb||||false|false\u00bb custom_css_main_element=\u00bbtext-align: center;\u00bb border_radii_photo_border=\u00bbon|200px|200px|200px|200px\u00bb border_width_all_photo_border=\u00bb5px\u00bb border_color_all_photo_border=\u00bb#13678a\u00bb global_colors_info=\u00bb{}\u00bb][\/difl_advanced_person][difl_dual_button btn_left_background_bgcolor=\u00bb#13678a\u00bb btn_left_font_icon=\u00bb&#xe023;||divi||400&#8243; btn_left_icon_color=\u00bb#FFFFFF\u00bb btn_left_icon_placement=\u00bbleft\u00bb btn_right_background_background_image=\u00bbhttps:\/\/emfoco.med.br\/wp-content\/uploads\/2024\/02\/iconewhatsapp1.webp\u00bb btn_right_background_background_image_size=\u00bbfit\u00bb btn_right_background_size_width=\u00bb100%\u00bb btn_right_background_size_height=\u00bb100%\u00bb use_right_button_icon=\u00bboff\u00bb left_button=\u00bbReservar en l\u00ednea\u00bb left_button_url=\u00bbhttps:\/\/api.whatsapp.com\/send\/?phone=\u200e551132893195&amp;text=Ol%C3%A1%2C+vim+do+site+e+gostaria+de+mais+informa%C3%A7%C3%B5es+sobre+exame+com+o+Dr.+Ricardo+Guerra.&amp;type=phone_number&amp;app_absent=0&#8243; left_button_target=\u00bbon\u00bb right_button=\u00bb_\u00bb right_button_url=\u00bbhttps:\/\/api.whatsapp.com\/send\/?phone=\u200e551132893195&amp;text=Ol%C3%A1%2C+vim+do+site+e+gostaria+de+mais+informa%C3%A7%C3%B5es+sobre+exame+com+o+Dr.+Ricardo+Guerra.&amp;type=phone_number&amp;app_absent=0&#8243; right_button_target=\u00bbon\u00bb right_button_wrapper_margin=\u00bb|||20px|false|false\u00bb left_button_padding=\u00bb10px|40px|10px|40px|false|false\u00bb alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb left_button_text_color=\u00bb#FFFFFF\u00bb left_button_font_size=\u00bb16px\u00bb right_button_text_color=\u00bb#FFFFFF\u00bb right_button_font_size=\u00bb16px\u00bb border_radii_left_button=\u00bbon|10px|10px|10px|10px\u00bb global_colors_info=\u00bb{}\u00bb][\/difl_dual_button][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_2_font_size=\u00bb22px\u00bb header_2_line_height=\u00bb1.8em\u00bb header_3_font=\u00bb||||||||\u00bb header_3_text_color=\u00bb#116789&#8243; header_3_font_size=\u00bb17px\u00bb header_3_line_height=\u00bb2em\u00bb header_5_text_color=\u00bb#116789&#8243; header_5_line_height=\u00bb0.8em\u00bb width=\u00bb90%\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb||||false|true\u00bb custom_padding=\u00bb|25px||25px|false|true\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Mi historia<\/h2>\n<p><a href=\"https:\/\/emfoco.med.br\/medico-endoscopista-conheca-o-dr-ricardo-guerra\/\" target=\"_blank\" rel=\"noopener\">El Dr. Ricardo Guerra Almeida<\/a> es endoscopista por la Escola Paulista de Medicina da Universidade Federal de S\u00e3o Paulo (EPM\/UNIFESP). Se ha subespecializado en Fisiolog\u00eda Gastrointestinal en el Hospital Israelita Albert Einstein y en Colangiopancreatograf\u00eda Endosc\u00f3pica Retr\u00f3grada en el Hospital Sancta Maggiore &#8211; Instituto Prevent Senior. <\/p>\n<p>Trabaja principalmente en el diagn\u00f3stico de enfermedades esof\u00e1gicas y en pruebas como la monitorizaci\u00f3n del pH y la manometr\u00eda esof\u00e1gica.<\/p>\n<p class=\"font_6\">[\/et_pb_text][difl_faq faq_layout=\u00bbtoggle\u00bb close_icon_color=\u00bb#13678a\u00bb faq_wrapper_margin=\u00bb30px|10px|30px|10px|false|true\u00bb faq_item_wrapper_margin=\u00bb||||false|false\u00bb faq_item_per_column_tablet=\u00bb2&#8243; faq_item_per_column_phone=\u00bb1&#8243; faq_item_per_column_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb question_text_font_size=\u00bb18px\u00bb border_width_all_faq_item_wrapper_border=\u00bb0px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb que_wrapper_bg_bgcolor__hover=\u00bb1px||||false|false\u00bb que_wrapper_bg_bgcolor__hover_enabled=\u00bbon|hover\u00bb][difl_faqitem question=\u00bbEspecialidade m\u00e9dica\u00bb ans_img_padding=\u00bb||||false|false\u00bb _builder_version=\u00bb4.27.4&#8243; global_colors_info=\u00bb{}\u00bb que_wrapper_bg_bgcolor__hover=\u00bb1px||||false|false\u00bb que_wrapper_bg_bgcolor__hover_enabled=\u00bbon|hover\u00bb]<\/p>\n<p>Endoscopia<\/p>\n<p>[\/difl_faqitem][difl_faqitem question=\u00bbSubespecializa\u00e7\u00e3o\u00bb ans_img_padding=\u00bb||||false|false\u00bb _builder_version=\u00bb4.27.4&#8243; global_colors_info=\u00bb{}\u00bb que_wrapper_bg_bgcolor__hover=\u00bb1px||||false|false\u00bb que_wrapper_bg_bgcolor__hover_enabled=\u00bbon|hover\u00bb]<\/p>\n<p>Fisiologia Gastrointestinal<\/p>\n<p>Colangiopancreatografia Endosc\u00f3pica Retr\u00f3grada<\/p>\n<p>[\/difl_faqitem][difl_faqitem question=\u00bbHospitais de refer\u00eancia\u00bb ans_img_padding=\u00bb||||false|false\u00bb _builder_version=\u00bb4.27.4&#8243; global_colors_info=\u00bb{}\u00bb que_wrapper_bg_bgcolor__hover=\u00bb1px||||false|false\u00bb que_wrapper_bg_bgcolor__hover_enabled=\u00bbon|hover\u00bb]<\/p>\n<p>Hospital S\u00e3o Paulo<\/p>\n<p>Hospital S\u00e3o Crist\u00f3v\u00e3o<\/p>\n<p>Hospital Prevent Senior<\/p>\n<p>[\/difl_faqitem][difl_faqitem question=\u00bbForma\u00e7\u00e3o profissional\u00bb ans_img_padding=\u00bb||||false|false\u00bb _builder_version=\u00bb4.27.4&#8243; global_colors_info=\u00bb{}\u00bb que_wrapper_bg_bgcolor__hover=\u00bb1px||||false|false\u00bb que_wrapper_bg_bgcolor__hover_enabled=\u00bbon|hover\u00bb]<\/p>\n<h6 class=\"font_6\">Gradua\u00e7\u00e3o:<\/h6>\n<ul>\n<li class=\"font_6\">Centro Universit\u00e1rio do Estado do Par\u00e1<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h6 class=\"font_6\">Resid\u00eancias:<\/h6>\n<ul>\n<li class=\"font_6\">Cl\u00ednica M\u00e9dica pela Escola Paulista de Medicina da Universidade Federal de S\u00e3o Paulo (EPM\/UNIFESP).<\/li>\n<li class=\"font_6\">Endoscopia pela Escola Paulista de Medicina da Universidade Federal de S\u00e3o Paulo (EPM\/UNIFESP).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h6>Subespecializa\u00e7\u00f5es e aperfei\u00e7oamentos:<\/h6>\n<ul>\n<li>Fisiologia Gastrointestinal pelo Hospital Israelita Albert Einstein<\/li>\n<li>Colangiopancreatografia Endosc\u00f3pica Retr\u00f3grada pelo Hospital Sancta Maggiore &#8211; Instituto Prevent Senior<\/li>\n<\/ul>\n<ul class=\"font_6\"><\/ul>\n<ul class=\"font_6\"><\/ul>\n<ul class=\"font_6\"><\/ul>\n<ul class=\"font_6\"><\/ul>\n<ul class=\"font_6\"><\/ul>\n<ul class=\"font_6\"><\/ul>\n<ul class=\"font_6\"><\/ul>\n<ul class=\"font_6\"><\/ul>\n<ul class=\"font_6\"><\/ul>\n<ul class=\"font_6\"><\/ul>\n<ul class=\"font_6\"><\/ul>\n<ul class=\"font_6\"><\/ul>\n<ul class=\"font_6\"><\/ul>\n<ul class=\"font_6\"><\/ul>\n<ul class=\"font_6\"><\/ul>\n<p>[\/difl_faqitem][difl_faqitem question=\u00bb\u00c1reas de atua\u00e7\u00e3o e experi\u00eancia profissional\u00bb ans_img_padding=\u00bb||||false|false\u00bb _builder_version=\u00bb4.27.4&#8243; global_colors_info=\u00bb{}\u00bb que_wrapper_bg_bgcolor__hover=\u00bb1px||||false|false\u00bb que_wrapper_bg_bgcolor__hover_enabled=\u00bbon|hover\u00bb]<\/p>\n<h6>Endoscopia:<\/h6>\n<ul>\n<li>Endoscopia Digestiva Alta<\/li>\n<li>Endoscopia Digestiva Baixa<\/li>\n<li>Colangiopancreatografia Endosc\u00f3pica Retr\u00f3grada<\/li>\n<li>Manometria esof\u00e1gica<\/li>\n<li>pHmetria esof\u00e1gica<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h6>Fisiologia gastrointestinal:<\/h6>\n<ul>\n<li>Acalasia idiop\u00e1tica<\/li>\n<li>Altera\u00e7\u00f5es motoras do es\u00f4fago<\/li>\n<li>Dificuldade ou dor para engolir<\/li>\n<li>Disfagias faringo-esof\u00e1gicas<\/li>\n<li>Disfagias funcionais<\/li>\n<li>Divert\u00edculos do es\u00f4fago<\/li>\n<li>Doen\u00e7a do refluxo gastroesof\u00e1gico<\/li>\n<li>Dor tor\u00e1cica de origem n\u00e3o card\u00edaca<\/li>\n<li>Engasgo<\/li>\n<li>Esclerodermia<\/li>\n<li>Espasmo difuso<\/li>\n<li>Impedanciophmetria esof\u00e1gica<\/li>\n<li>Localiza\u00e7\u00e3o da sonda de pH<\/li>\n<li>Megaes\u00f4fago<\/li>\n<li>N\u00e1useas recorrentes<\/li>\n<li>Pr\u00e9-operat\u00f3rio<\/li>\n<li>Queima\u00e7\u00e3o retroesternal<\/li>\n<li>Regurgita\u00e7\u00e3o alimentar<\/li>\n<li>Sensa\u00e7\u00e3o de entalamento<\/li>\n<li>V\u00f4mitos recorrentes<\/li>\n<\/ul>\n<ul><\/ul>\n<p>&nbsp;<\/p>\n<p>[\/difl_faqitem][\/difl_faq][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.23&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.23&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/emfoco.med.br\/wp-content\/uploads\/2025\/04\/Endoscopia.webp\u00bb title_text=\u00bbEndoscopia\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb38%\u00bb module_alignment=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_2_font_size=\u00bb19px\u00bb header_2_line_height=\u00bb1.8em\u00bb header_5_text_color=\u00bb#116789&#8243; header_5_line_height=\u00bb1.1em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb-15px||||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Endoscopia<\/h2>\n<h5>Endoscopia digestiva alta<\/h5>\n<h5>Endoscopia digestiva baja<\/h5>\n<h5>Colangiopancreatograf\u00eda retr\u00f3grada endosc\u00f3pica<\/h5>\n<h5>Manometr\u00eda esof\u00e1gica<\/h5>\n<h5>Monitorizaci\u00f3n del pH esof\u00e1gico<\/h5>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.23&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/emfoco.med.br\/wp-content\/uploads\/2025\/04\/Fisiologia-gastrointestinal.webp\u00bb title_text=\u00bbFisiolog\u00eda gastrointestinal\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb38%\u00bb module_alignment=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_2_font_size=\u00bb19px\u00bb header_2_line_height=\u00bb1.8em\u00bb header_5_text_color=\u00bb#116789&#8243; header_5_line_height=\u00bb1.3em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb-15px||||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Fisiolog\u00eda gastrointestinal<\/h2>\n<h5>Acalasia idiop\u00e1tica<\/h5>\n<h5>Cambios motores en el es\u00f3fago<\/h5>\n<h5>Dificultad o dolor al tragar<\/h5>\n<h5>Disfagia faringoesof\u00e1gica<\/h5>\n<h5>Disfagia funcional<\/h5>\n<h5>Divert\u00edculos esof\u00e1gicos<\/h5>\n<h5>Enfermedad por reflujo gastroesof\u00e1gico<\/h5>\n<h5>Dolor tor\u00e1cico de origen no card\u00edaco<\/h5>\n<h5>Asfixia<\/h5>\n<h5>Esclerodermia<\/h5>\n<h5>Espasmo difuso<\/h5>\n<h5>Impedanciometr\u00eda esof\u00e1gica<\/h5>\n<h5>Ubicaci\u00f3n de la sonda de pH<\/h5>\n<h5>Megaes\u00f3fago<\/h5>\n<h5>N\u00e1useas recurrentes<\/h5>\n<h5>Preoperatorio<\/h5>\n<h5>Quemadura retroesternal<\/h5>\n<h5>Regurgitaci\u00f3n alimentaria<\/h5>\n<h5>Sensaci\u00f3n de atrapamiento<\/h5>\n<h5>V\u00f3mitos recurrentes<\/h5>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_video src=\u00bbhttps:\/\/youtu.be\/z3ReBjoP5DQ\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/api.whatsapp.com\/send\/?phone=\u200e551132893195&amp;text=Ol%C3%A1%2C+vim+do+site+e+gostaria+de+mais+informa%C3%A7%C3%B5es+sobre+exame+com+o+Dr.+Ricardo+Guerra.&amp;type=phone_number&amp;app_absent=0&#8243; url_new_window=\u00bbon\u00bb button_text=\u00bbReserve su cita\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#196586&#8243; button_border_color=\u00bb#196586&#8243; button_border_radius=\u00bb20px\u00bb button_font=\u00bb|600|||||||\u00bb button_icon=\u00bb&#x45;||divi||400&#8243; button_icon_color=\u00bb#FFFFFF\u00bb button_on_hover=\u00bboff\u00bb custom_margin=\u00bb15px||||false|false\u00bb button_text_size_tablet=\u00bb18px\u00bb button_text_size_phone=\u00bb13px\u00bb button_text_size_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bboff|off|on\u00bb _builder_version=\u00bb4.23&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb70%\u00bb max_width=\u00bb100%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.23&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/emfoco.med.br\/wp-content\/uploads\/2025\/04\/Endoscopia.webp\u00bb title_text=\u00bbEndoscopia\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb50%\u00bb module_alignment=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_2_font_size=\u00bb19px\u00bb header_2_line_height=\u00bb1.8em\u00bb header_5_text_color=\u00bb#116789&#8243; header_5_line_height=\u00bb1.1em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb-15px||||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Endoscopia<\/h2>\n<h5>Endoscopia digestiva alta<\/h5>\n<h5>Endoscopia digestiva baja<\/h5>\n<h5>Colangiopancreatograf\u00eda retr\u00f3grada endosc\u00f3pica<\/h5>\n<h5>Manometr\u00eda esof\u00e1gica<\/h5>\n<h5>Monitorizaci\u00f3n del pH esof\u00e1gico<\/h5>\n<p>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/emfoco.med.br\/wp-content\/uploads\/2025\/04\/Fisiologia-gastrointestinal.webp\u00bb title_text=\u00bbFisiolog\u00eda gastrointestinal\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb50%\u00bb module_alignment=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_2_font_size=\u00bb19px\u00bb header_2_line_height=\u00bb1.8em\u00bb header_5_text_color=\u00bb#116789&#8243; header_5_line_height=\u00bb1.3em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb-15px||||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Fisiolog\u00eda gastrointestinal<\/h2>\n<h5>Acalasia idiop\u00e1tica<\/h5>\n<h5>Cambios motores en el es\u00f3fago<\/h5>\n<h5>Dificultad o dolor al tragar<\/h5>\n<h5>Disfagia faringoesof\u00e1gica<\/h5>\n<h5>Disfagia funcional<\/h5>\n<h5>Divert\u00edculos esof\u00e1gicos<\/h5>\n<h5>Enfermedad por reflujo gastroesof\u00e1gico<\/h5>\n<h5>Dolor tor\u00e1cico de origen no card\u00edaco<\/h5>\n<h5>Asfixia<\/h5>\n<h5>Esclerodermia<\/h5>\n<h5>Espasmo difuso<\/h5>\n<h5>Impedanciometr\u00eda esof\u00e1gica<\/h5>\n<h5>Ubicaci\u00f3n de la sonda de pH<\/h5>\n<h5>Megaes\u00f3fago<\/h5>\n<h5>N\u00e1useas recurrentes<\/h5>\n<h5>Preoperatorio<\/h5>\n<h5>Quemadura retroesternal<\/h5>\n<h5>Regurgitaci\u00f3n alimentaria<\/h5>\n<h5>Sensaci\u00f3n de atrapamiento<\/h5>\n<h5>V\u00f3mitos recurrentes<\/h5>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_video src=\u00bbhttps:\/\/youtu.be\/z3ReBjoP5DQ\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb-21px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/api.whatsapp.com\/send\/?phone=\u200e551132893195&amp;text=Ol%C3%A1%2C+vim+do+site+e+gostaria+de+mais+informa%C3%A7%C3%B5es+sobre+exame+com+o+Dr.+Ricardo+Guerra.&amp;type=phone_number&amp;app_absent=0&#8243; url_new_window=\u00bbon\u00bb button_text=\u00bbReserve su cita\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#196586&#8243; button_border_color=\u00bb#196586&#8243; button_border_radius=\u00bb20px\u00bb button_font=\u00bb|600|||||||\u00bb button_icon=\u00bb&#x45;||divi||400&#8243; button_icon_color=\u00bb#FFFFFF\u00bb button_on_hover=\u00bboff\u00bb button_text_size_tablet=\u00bb18px\u00bb button_text_size_phone=\u00bb13px\u00bb button_text_size_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conozca al Dr. Ricardo Guerra Almeida, endoscopista y miembro del equipo de especialistas de Medicina em Foco.<\/p>\n","protected":false},"author":1,"featured_media":294936,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","rank_math_focus_keyword":"ricardo guerra, endoscopista","rank_math_title":"Dr Ricardo Guerra - Instituto Medicina em Foco","rank_math_description":"Conozca al Dr. Ricardo Guerra Almeida, endoscopista y miembro del equipo de especialistas de Medicina em Foco.","rank_math_og_title":"","rank_math_og_description":"","rank_math_og_image":"","rank_math_og_image_id":"","rank_math_twitter_title":"","rank_math_twitter_description":"","rank_math_twitter_image":"","rank_math_canonical_url":"","rank_math_robots":"","rank_math_rich_snippet":"","rank_math_snippet_name":"","rank_math_snippet_desc":"","rank_math_seo_score":"","rank_math_pillar_content":"","footnotes":""},"false":[],"class_list":["post-294934","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-endoscopia-es"],"_links":{"self":[{"href":"https:\/\/emfoco.med.br\/es\/wp-json\/wp\/v2\/project\/294934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emfoco.med.br\/es\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/emfoco.med.br\/es\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/emfoco.med.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emfoco.med.br\/es\/wp-json\/wp\/v2\/comments?post=294934"}],"version-history":[{"count":6,"href":"https:\/\/emfoco.med.br\/es\/wp-json\/wp\/v2\/project\/294934\/revisions"}],"predecessor-version":[{"id":296587,"href":"https:\/\/emfoco.med.br\/es\/wp-json\/wp\/v2\/project\/294934\/revisions\/296587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emfoco.med.br\/es\/wp-json\/wp\/v2\/media\/294936"}],"wp:attachment":[{"href":"https:\/\/emfoco.med.br\/es\/wp-json\/wp\/v2\/media?parent=294934"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/emfoco.med.br\/es\/wp-json\/wp\/v2\/false?post=294934"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/emfoco.med.br\/es\/wp-json\/wp\/v2\/false?post=294934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}